{"id":122,"count":37,"description":"","link":"https:\/\/test-web.casino-jpn.net\/online\/tag\/vegawallet\/","name":"\u30d9\u30ac\u30a6\u30a9\u30ec\u30c3\u30c8","slug":"vegawallet","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/tags\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/posts?tags=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}