{"id":123,"count":40,"description":"","link":"https:\/\/test-web.casino-jpn.net\/online\/tag\/ecopayz\/","name":"\u30da\u30a4\u30ba\uff3b\u65e7\u30a8\u30b3\u30da\u30a4\u30ba\uff3d","slug":"ecopayz","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/tags\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/posts?tags=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}