{"id":124,"count":18,"description":"","link":"https:\/\/test-web.casino-jpn.net\/online\/tag\/sticpay\/","name":"\u30b9\u30c6\u30a3\u30c3\u30af\u30da\u30a4","slug":"sticpay","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/tags\/124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/posts?tags=124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}