{"id":87,"count":15,"description":"","link":"https:\/\/test-web.casino-jpn.net\/online\/tag\/mystino\/","name":"\u30df\u30b9\u30c6\u30a3\u30fc\u30ce","slug":"mystino","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/tags\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/test-web.casino-jpn.net\/online\/wp-json\/wp\/v2\/posts?tags=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}